{"id":2135,"count":3,"description":"Zilveti Advogados has a specialized team, focused on acting in strategic litigation, working reventively with clients as enablers of practical and individualized solutions in the various forms of business claims.\n","link":"https:\/\/zilveti.com.br\/en\/corporate\/civel-en\/","name":"C\u00edvel","slug":"civel-en","taxonomy":"categoria-areas-de-atuacao","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.9 (Yoast SEO v27.9) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Direito Civil - Zilveti Advogados<\/title>\n<meta name=\"description\" content=\"O Zilveti Advogados oferece servi\u00e7os especializados em demandas empresariais de alta complexidade, com solu\u00e7\u00f5es personalizadas desde a estrutura\u00e7\u00e3o dos neg\u00f3cios at\u00e9 a gest\u00e3o de crises.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/zilveti.com.br\/corporate\/civel\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Arquivo de C\u00edvel\" \/>\n<meta property=\"og:description\" content=\"O Zilveti Advogados oferece servi\u00e7os especializados em demandas empresariais de alta complexidade, com solu\u00e7\u00f5es personalizadas desde a estrutura\u00e7\u00e3o dos neg\u00f3cios at\u00e9 a gest\u00e3o de crises.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/zilveti.com.br\/corporate\/civel\/\" \/>\n<meta property=\"og:site_name\" content=\"Zilveti Advogados\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/zilveti.com.br\\\/corporate\\\/civel\\\/\",\"url\":\"https:\\\/\\\/zilveti.com.br\\\/corporate\\\/civel\\\/\",\"name\":\"Direito Civil - Zilveti Advogados\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/zilveti.com.br\\\/#website\"},\"description\":\"O Zilveti Advogados oferece servi\u00e7os especializados em demandas empresariais de alta complexidade, com solu\u00e7\u00f5es personalizadas desde a estrutura\u00e7\u00e3o dos neg\u00f3cios at\u00e9 a gest\u00e3o de crises.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/zilveti.com.br\\\/corporate\\\/civel\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/zilveti.com.br\\\/corporate\\\/civel\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/zilveti.com.br\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"C\u00edvel\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/zilveti.com.br\\\/#website\",\"url\":\"https:\\\/\\\/zilveti.com.br\\\/\",\"name\":\"Zilveti Advogados\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/zilveti.com.br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Direito Civil - Zilveti Advogados","description":"O Zilveti Advogados oferece servi\u00e7os especializados em demandas empresariais de alta complexidade, com solu\u00e7\u00f5es personalizadas desde a estrutura\u00e7\u00e3o dos neg\u00f3cios at\u00e9 a gest\u00e3o de crises.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/zilveti.com.br\/corporate\/civel\/","og_locale":"en_US","og_type":"article","og_title":"Arquivo de C\u00edvel","og_description":"O Zilveti Advogados oferece servi\u00e7os especializados em demandas empresariais de alta complexidade, com solu\u00e7\u00f5es personalizadas desde a estrutura\u00e7\u00e3o dos neg\u00f3cios at\u00e9 a gest\u00e3o de crises.","og_url":"https:\/\/zilveti.com.br\/corporate\/civel\/","og_site_name":"Zilveti Advogados","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/zilveti.com.br\/corporate\/civel\/","url":"https:\/\/zilveti.com.br\/corporate\/civel\/","name":"Direito Civil - Zilveti Advogados","isPartOf":{"@id":"https:\/\/zilveti.com.br\/#website"},"description":"O Zilveti Advogados oferece servi\u00e7os especializados em demandas empresariais de alta complexidade, com solu\u00e7\u00f5es personalizadas desde a estrutura\u00e7\u00e3o dos neg\u00f3cios at\u00e9 a gest\u00e3o de crises.","breadcrumb":{"@id":"https:\/\/zilveti.com.br\/corporate\/civel\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/zilveti.com.br\/corporate\/civel\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/zilveti.com.br\/en\/"},{"@type":"ListItem","position":2,"name":"C\u00edvel"}]},{"@type":"WebSite","@id":"https:\/\/zilveti.com.br\/#website","url":"https:\/\/zilveti.com.br\/","name":"Zilveti Advogados","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/zilveti.com.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/zilveti.com.br\/en\/wp-json\/wp\/v2\/categoria-areas-de-atuacao\/2135","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/zilveti.com.br\/en\/wp-json\/wp\/v2\/categoria-areas-de-atuacao"}],"about":[{"href":"https:\/\/zilveti.com.br\/en\/wp-json\/wp\/v2\/taxonomies\/categoria-areas-de-atuacao"}],"wp:post_type":[{"href":"https:\/\/zilveti.com.br\/en\/wp-json\/wp\/v2\/areas-de-atuacao?categoria-areas-de-atuacao=2135"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}